{"id":130,"date":"2013-02-16T12:53:00","date_gmt":"2013-02-16T12:53:00","guid":{"rendered":"http:\/\/blog.hotelpalmeral.com\/?p=130"},"modified":"2013-02-16T12:53:00","modified_gmt":"2013-02-16T12:53:00","slug":"farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm","status":"publish","type":"post","link":"https:\/\/hotelpalmeral.com\/fr\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/","title":{"rendered":"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm"},"content":{"rendered":"<p>Esperamos que no sea necesario, pero por si acaso, os pasamos un listado con las farmacias que tendr\u00e9is de guardia aqu\u00ed en Benidorm esta segunda quincena de febrero:<\/p>\n<p>-D\u00eda 15\/02\/2013: La farmacia que est\u00e1 en la C\/aAlameda, 4.<br \/>-D\u00eda 16\/02\/2013: La farmacia que est\u00e1 en la Avd. Mediterr\u00e1neo, 3. Local 1.<br \/>-D\u00eda 17\/02\/2013: La farmacia que est\u00e1 en la Avd. Europa,6.<br \/>-D\u00eda 18\/02\/2013: La farmacia que est\u00e1 en la Avd. Alcoy,16.<br \/>-D\u00eda 19\/02\/2013: La farmacia que est\u00e1 en la Avd. Alfonso Puchades,14.<br \/>-D\u00eda 20\/02\/2013: La farmacia que est\u00e1 en la Avd. Portugal,4. Esq. Holanda Playmon.<br \/>-D\u00eda 21\/02\/2013: La farmacia que est\u00e1 en la Avd. Villajoyosa,4 Edf. Altamira V.<br \/>-D\u00eda 22\/02\/2013: La farmacia que est\u00e1 en la C\/Valencia,4. Edf. Beatriz, local6.<br \/>-D\u00eda 23\/02\/2013: La farmacia que est\u00e1 en la C\/Montera,4.<br \/>-D\u00eda 24\/02\/2013: La farmacia que est\u00e1 en la Avd. Nicaragua,15.<br \/>-D\u00eda 25\/02\/2013: La farmacia que est\u00e1 en la C\/Ruzafa,14, edif.Cristal Park, local 2.<br \/>-D\u00eda 26\/02\/2013: La farmacia que est\u00e1 en la C\/Tom\u00e1s Ortu\u00f1o,71 esquina C\/Buen Pastor.<br \/>-D\u00eda 27\/02\/2013: La farmacia que est\u00e1 en la Avd.Beniard\u00e1, 31.<br \/>-D\u00eda 28\/02\/2013: La farmacia que est\u00e1 en la Paseo Carretera,27.<\/p>\n<p>Adem\u00e1s y como siempre est\u00e1n:<br \/>&#8211; Farmacia 24h en la Avd. Mediterr\u00e1neo,29, edf. coblanca 41, local1.<br \/>&#8211; Farmacia 12h los 365 d\u00edas en la AVd. Villajoyosa 4 edificio Alatamira V.<\/p>\n<p>Esperamos seros de ayuda<br \/>Un saludo<\/p>\n<p>Hotel El Palmeral, <a href=\"https:\/\/hotelpalmeral.com\/fr\/\">Hotel en la Playa de Benidorm<\/a><br \/><a href=\"https:\/\/hotelpalmeral.com\/fr\/\">www.hotelpalmeral.com<\/a><br \/>Telf.: 965 850 176<\/p>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s1600\/logo+780x2000+pixels.png\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"77\" src=\"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s200\/logo+780x2000+pixels.png\" width=\"200\"><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Esperamos que no sea necesario, pero por si acaso, os pasamos un listado con las farmacias que tendr\u00e9is de guardia aqu\u00ed en Benidorm esta segunda quincena de febrero: -D\u00eda 15\/02\/2013: La farmacia que est\u00e1 en la C\/aAlameda, 4.-D\u00eda 16\/02\/2013: La farmacia que est\u00e1 en la Avd. Mediterr\u00e1neo, 3. Local 1.-D\u00eda 17\/02\/2013: La farmacia que est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-130","post","type-post","status-publish","format-standard","hentry","category-informacion-practica-de-benidorm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm - Hotel El Palmeral<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/hotelpalmeral.com\/fr\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm - Hotel El Palmeral\" \/>\r\n<meta property=\"og:description\" content=\"Esperamos que no sea necesario, pero por si acaso, os pasamos un listado con las farmacias que tendr\u00e9is de guardia aqu\u00ed en Benidorm esta segunda quincena de febrero: -D\u00eda 15\/02\/2013: La farmacia que est\u00e1 en la C\/aAlameda, 4.-D\u00eda 16\/02\/2013: La farmacia que est\u00e1 en la Avd. Mediterr\u00e1neo, 3. Local 1.-D\u00eda 17\/02\/2013: La farmacia que est\u00e1 [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/hotelpalmeral.com\/fr\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hotel El Palmeral\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HotelPalmeralBenidorm\" \/>\r\n<meta property=\"article:published_time\" content=\"2013-02-16T12:53:00+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s200\/logo+780x2000+pixels.png\" \/>\r\n<meta name=\"author\" content=\"admin_palmeral\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hotelelpalmeral\" \/>\r\n<meta name=\"twitter:site\" content=\"@hotelelpalmeral\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_palmeral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/\"},\"author\":{\"name\":\"admin_palmeral\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/person\\\/c8066d1b13fdf1bac6d45a1394738ca6\"},\"headline\":\"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm\",\"datePublished\":\"2013-02-16T12:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/\"},\"wordCount\":250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-97gmraH3yrI\\\/UR-A3kr6SRI\\\/AAAAAAAADHU\\\/KOyHIsysE_k\\\/s200\\\/logo+780x2000+pixels.png\",\"articleSection\":[\"Informaci\u00f3n pr\u00e1ctica de Benidorm\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/\",\"name\":\"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm - Hotel El Palmeral\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-97gmraH3yrI\\\/UR-A3kr6SRI\\\/AAAAAAAADHU\\\/KOyHIsysE_k\\\/s200\\\/logo+780x2000+pixels.png\",\"datePublished\":\"2013-02-16T12:53:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#primaryimage\",\"url\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-97gmraH3yrI\\\/UR-A3kr6SRI\\\/AAAAAAAADHU\\\/KOyHIsysE_k\\\/s200\\\/logo+780x2000+pixels.png\",\"contentUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-97gmraH3yrI\\\/UR-A3kr6SRI\\\/AAAAAAAADHU\\\/KOyHIsysE_k\\\/s200\\\/logo+780x2000+pixels.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hotelpalmeral.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#website\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/\",\"name\":\"Hotel El Palmeral\",\"description\":\"Hotel en Benidorm\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotelpalmeral.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#organization\",\"name\":\"Hotel El Palmeral\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo-footer.png\",\"contentUrl\":\"https:\\\/\\\/hotelpalmeral.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo-footer.png\",\"width\":229,\"height\":265,\"caption\":\"Hotel El Palmeral\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HotelPalmeralBenidorm\",\"https:\\\/\\\/x.com\\\/hotelelpalmeral\",\"https:\\\/\\\/www.instagram.com\\\/hotelpalmeralbenidorm\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/person\\\/c8066d1b13fdf1bac6d45a1394738ca6\",\"name\":\"admin_palmeral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g\",\"caption\":\"admin_palmeral\"},\"sameAs\":[\"http:\\\/\\\/hotelpalmeral.com\"],\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/fr\\\/author\\\/admin_palmeral\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm - Hotel El Palmeral","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelpalmeral.com\/fr\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/","og_locale":"fr_FR","og_type":"article","og_title":"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm - Hotel El Palmeral","og_description":"Esperamos que no sea necesario, pero por si acaso, os pasamos un listado con las farmacias que tendr\u00e9is de guardia aqu\u00ed en Benidorm esta segunda quincena de febrero: -D\u00eda 15\/02\/2013: La farmacia que est\u00e1 en la C\/aAlameda, 4.-D\u00eda 16\/02\/2013: La farmacia que est\u00e1 en la Avd. Mediterr\u00e1neo, 3. Local 1.-D\u00eda 17\/02\/2013: La farmacia que est\u00e1 [&hellip;]","og_url":"https:\/\/hotelpalmeral.com\/fr\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/","og_site_name":"Hotel El Palmeral","article_publisher":"https:\/\/www.facebook.com\/HotelPalmeralBenidorm","article_published_time":"2013-02-16T12:53:00+00:00","og_image":[{"url":"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s200\/logo+780x2000+pixels.png","type":"","width":"","height":""}],"author":"admin_palmeral","twitter_card":"summary_large_image","twitter_creator":"@hotelelpalmeral","twitter_site":"@hotelelpalmeral","twitter_misc":{"\u00c9crit par":"admin_palmeral","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#article","isPartOf":{"@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/"},"author":{"name":"admin_palmeral","@id":"https:\/\/hotelpalmeral.com\/#\/schema\/person\/c8066d1b13fdf1bac6d45a1394738ca6"},"headline":"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm","datePublished":"2013-02-16T12:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/"},"wordCount":250,"commentCount":0,"publisher":{"@id":"https:\/\/hotelpalmeral.com\/#organization"},"image":{"@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s200\/logo+780x2000+pixels.png","articleSection":["Informaci\u00f3n pr\u00e1ctica de Benidorm"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/","url":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/","name":"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm - Hotel El Palmeral","isPartOf":{"@id":"https:\/\/hotelpalmeral.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#primaryimage"},"image":{"@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s200\/logo+780x2000+pixels.png","datePublished":"2013-02-16T12:53:00+00:00","breadcrumb":{"@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#primaryimage","url":"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s200\/logo+780x2000+pixels.png","contentUrl":"http:\/\/3.bp.blogspot.com\/-97gmraH3yrI\/UR-A3kr6SRI\/AAAAAAAADHU\/KOyHIsysE_k\/s200\/logo+780x2000+pixels.png"},{"@type":"BreadcrumbList","@id":"https:\/\/hotelpalmeral.com\/farmacias-de-guardia-la-2a-quincena-de-febrero-en-benidorm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hotelpalmeral.com\/"},{"@type":"ListItem","position":2,"name":"Farmacias de guardia la 2\u00aa quincena de febrero en Benidorm"}]},{"@type":"WebSite","@id":"https:\/\/hotelpalmeral.com\/#website","url":"https:\/\/hotelpalmeral.com\/","name":"Hotel El Palmeral","description":"Hotel en Benidorm","publisher":{"@id":"https:\/\/hotelpalmeral.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelpalmeral.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hotelpalmeral.com\/#organization","name":"Hotel El Palmeral","url":"https:\/\/hotelpalmeral.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hotelpalmeral.com\/#\/schema\/logo\/image\/","url":"https:\/\/hotelpalmeral.com\/wp-content\/uploads\/2023\/03\/Logo-footer.png","contentUrl":"https:\/\/hotelpalmeral.com\/wp-content\/uploads\/2023\/03\/Logo-footer.png","width":229,"height":265,"caption":"Hotel El Palmeral"},"image":{"@id":"https:\/\/hotelpalmeral.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HotelPalmeralBenidorm","https:\/\/x.com\/hotelelpalmeral","https:\/\/www.instagram.com\/hotelpalmeralbenidorm\/"]},{"@type":"Person","@id":"https:\/\/hotelpalmeral.com\/#\/schema\/person\/c8066d1b13fdf1bac6d45a1394738ca6","name":"admin_palmeral","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g","caption":"admin_palmeral"},"sameAs":["http:\/\/hotelpalmeral.com"],"url":"https:\/\/hotelpalmeral.com\/fr\/author\/admin_palmeral\/"}]}},"_links":{"self":[{"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":0,"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"wp:attachment":[{"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotelpalmeral.com\/fr\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}