{"id":1735,"date":"2012-11-07T16:59:00","date_gmt":"2012-11-07T16:59:00","guid":{"rendered":"http:\/\/blog.hotelpalmeral.com\/?p=177"},"modified":"2012-11-07T16:59:00","modified_gmt":"2012-11-07T16:59:00","slug":"programa-de-fiestas-patronales-de-benidorm-2012","status":"publish","type":"post","link":"https:\/\/hotelpalmeral.com\/en\/programa-de-fiestas-patronales-de-benidorm-2012\/","title":{"rendered":"Programa de fiestas Patronales de Benidorm 2012"},"content":{"rendered":"<p><b>VIERNES, 09 DE NOVIEMBRE<\/b><\/p>\n<p>18:00 h. &#8211; INAUGURACI\u00d3N OFICIAL DEL ALUMBRADO ARTISTICO, en la<\/p>\n<p>calle Mart\u00ednez Alejos por nuestra Reina Mayor la Srta. Andrea Ripoll Llorca ynuestra Reina Infantil la Ni\u00f1a Andrea Nieto Carrillo, junto a sus Cortes de Honor, acompa\u00f1ados por un grupo de m\u00fasicos de la prestigiosa Uni\u00f3n Musical de Benidorm.<\/p>\n<p>18:30 h. &#8211; Seguidamente las Reinas y su corte se trasladar\u00e1n al recinto ferial,situado junto a la Plaza de Toros, para proceder a la INAUGURACI\u00d3N DE LA FERIA. NOTA: D\u00eda popular del ni\u00f1o. Precios populares.<\/p>\n<p>20:00 h. &#8211; Visita del jurado a las calles participantes en el CONCURSO DE ENGALANAMIENTO DE CALLES, Trofeo \u201cPEPA ESPERANZA LLINARES LLORCA\u201d<\/p>\n<p>20:00 h. &#8211; Visita del jurado a las pe\u00f1as participantes en el CONCURSO DE<\/p>\n<p>ENGALANAMIENTO DE PE\u00d1AS<\/p>\n<p>22:30 h. &#8211; ENTRADA DE PE\u00d1AS. Concentraci\u00f3n de pe\u00f1as en la calle Ruzafa.<\/p>\n<p>Desfile de las pe\u00f1as asociadas por las calles Ruzafa y Mart\u00ednez Alejos.<\/p>\n<p><b>S\u00c1BADO, 10 DE NOVIEMBRE<\/b><\/p>\n<p>09:00 &#8211; 19:00 h. &#8211; Concurso provincial de PETANCA organizado por el club de petanca playa de Benidorm en las pistas de Mercasa.<\/p>\n<p>10:00 h. &#8211; SANTA MISA en la Iglesia Parroquial de San Jaime y Santa Ana en honor a nuestra excelsa Patrona la VIRGEN DEL SUFRAGIO.<\/p>\n<p>11:45 h. &#8211; APERTURA DE PUERTAS de la IGLESIA DE SAN JAIME y SANTA<\/p>\n<p>ANA, para cantar los Gozos a la Virgen del Sufragio e iniciar en su presencia las Fiestas Mayores Patronales 2012.<\/p>\n<p>12:00 h. &#8211; VOLTEO GENERAL DE CAMPANAS Y SUPER-BOMBARDEO A\u00c9REO anunciando el comienzo oficial de las Fiestas Mayores Patronales<\/p>\n<p>2012 desde la Plaza Castelar, a cargo de la prestigiosa Pirotecnia Pirofantas\u00eda Carlos Caballer.<\/p>\n<p>12:15 h. Desde la Plaza de San Jaime y acompa\u00f1ados de las Reinas y sus Cortes de Honor, Abanderado, Mayorales de Honor y Comisi\u00f3n de Fiestas Mayores Patronales 2012, se efectuar\u00e1 la ENTRADA DE LAS PRESTIGIOSAS BANDAS DE M\u00daSICA.<\/p>\n<p>13:00 h. CONCENTRACI\u00d3N DE BANDAS en la Plaza SS.MM. Los Reyes de<\/p>\n<p>Espa\u00f1a, donde interpretar\u00e1n todas juntas el pasodoble \u201cFIESTA EN BENIDORM\u201d, dirigidos por el maestro-autor de la obra, Sr. D. RAFAEL DOMENECH PARDO. Las Reinas de las fiestas impondr\u00e1n un corbat\u00edn a cada entidad musical.<\/p>\n<p>Al finalizar inauguraremos la CARPA DE LA COMISION 2012.<\/p>\n<p>16:30 h. XLIII Trofeo de Palomos Deportivos organizado por el Club de<\/p>\n<p>Colombicultura \u00abLa Isla\u00bb, en Barranco de Xixo.<\/p>\n<p>17:00 h. ESCENIFICACI\u00d3N DEL HALLAZGO DE NUESTRA PATRONA LA<\/p>\n<p>VIRGEN DEL SUFRAGIO representada en la Playa de Poniente por el cuadro de actores de la A.R.C. \u201cLa Barqueta\u201d, siguiendo el texto de D. Pere Mar\u00eda Orts i Bosch que nos traslada a aquel 16 de marzo de 1740 cuando se divis\u00f3 un llondro que iba a la deriva.<\/p>\n<p>BOMBARDEO A\u00c9REO a cargo de Pirofantas\u00eda Carlos Caballer<\/p>\n<p>17:30 h. Entrada de nuestra prestigiosa y querida Uni\u00f3n Musical de<\/p>\n<p>Benidorm.<\/p>\n<p>18:00 h. SOLEMNE ROMER\u00cdA.con el siguiente itinerario: Parque de Elche, Paseo de la Carretera, Alameda del Alcalde D. Pedro<\/p>\n<p>Zaragoza Orts, Calle Mayor y finalizando en la Plaza San Jaime.<\/p>\n<p>A la llegada de la Romer\u00eda a las puertas de la Iglesia San Jaime y Santa Ana, se llevar\u00e1 a cabo la OFRENDA DE FLORES, A LA VIRGEN DEL SUFRAGIO en la que todos los participantes dibujar\u00e1n los s\u00edmbolos de nuestra ciudad y nuestras fiestas.<\/p>\n<p>Al terminar, nuestra Reina Infantil, la ni\u00f1a Andrea Nieto Carrillo, recitar\u00e1 un verso escrito por Vicenta P\u00e9rez Bayona, \u201cCuqui\u201d, a nuestra Patrona y posteriormente, la Reina Mayor la Srta. Andrea Ripoll Llorca, dirigir\u00e1 un<\/p>\n<p>saludo a los asistentes y a todo el pueblo de Benidorm.<\/p>\n<p>Acto seguido tendr\u00e1 lugar el PREGON OFICIAL de las Fiestas Mayores<\/p>\n<p>Patronales 2012, a cargo del. Sr. D. MAT\u00cdAS P\u00c9REZ SUCH.<\/p>\n<p>Como broche final desde la plaza Castelar se disparar\u00e1 un magn\u00edfico CASTILLO de fuegos artificiales a cargo de Pirofantas\u00eda Carlos Caballer.<\/p>\n<p>00:30 h. GRAN CONCIERTO en el auditorio Julio Iglesias de MELENDI,<\/p>\n<p>cantante y autor de rumba mezclada con pop y rock y actual coach en el programa La Voz.<\/p>\n<p><b>DOMINGO, 11 DE NOVIEMBRE D\u00cdA DE LA VIRGEN DEL SUFRAGIO<\/b><\/p>\n<p>08:00 h. BOMBARDEO A\u00c9REO desde la plaza del Castillo.<\/p>\n<p>09:00-19:00 h. Concurso provincial de PETANCA organizado por el club de petanca playa de Benidorm en las pistas de Mercasa.<\/p>\n<p>10:30 h. Recogida de las Reinas de las Fiestas y sus Cortes de Honor por los Mayorales y Mayoralesas acompa\u00f1ados por las bandas de m\u00fasica, dirigi\u00e9ndose a la plaza de SSMM los Reyes de Espa\u00f1a, y hasta el Torrej\u00f3 desde donde, junto a las Autoridades de nuestra ciudad, se desplazar\u00e1n a la Iglesia de San Jaime y Santa Ana.<\/p>\n<p>10:30 h. Espectacular SUELTA DE VAQUILLAS en la Plaza de Toros por la<\/p>\n<p>empresa Viza-Arte y emoci\u00f3n. Queda terminantemente prohibida la presencia de menores de 16 a\u00f1os y personas ebrias en el callej\u00f3n y en el ruedo.<\/p>\n<p>11:00 h. XXVII TORNEO DE AJEDREZ Festes Majors Patronals 2012 organizado por el Club de Ajedrez Benidorm en el Hotel Deloix con una<\/p>\n<p>entrega de premios prevista para las 13:30 h.<\/p>\n<p>De 11:00 a 14:00 h. GRAN PARQUE INFANTIL en la Plaza SS.MM. los Reyes de Espa\u00f1a organizado conjuntamente por la Asociaci\u00f3n de Pe\u00f1as y la Comisi\u00f3n de Fiestas Mayores Patronales 2012.<\/p>\n<p>11:30 h. SOLEMNE CONCELEBRACI\u00d3N EUCAR\u00cdSTICA EN HONOR A<\/p>\n<p>NUESTRA EXCELSA PATRONA LA VIRGEN DEL SUFRAGIO, en la Iglesia de<\/p>\n<p>San Jaime y Santa Ana.<\/p>\n<p>BOMBARDEO a la salida de Misa.<\/p>\n<p>Al finalizar, PASACALLES a cargo de las bandas de la Comisi\u00f3n.<\/p>\n<p>De 13:00 a 14:00 h. Degustaci\u00f3n de cerveza por gentileza de cerveza Cruz Campo (hasta agotar existencias) en la plaza de SSMM Los Reyes de Espa\u00f1a.<\/p>\n<p>14:00 h. SUPERMASCLET\u00c1 DIGITAL, en la Plaza de la Hispanidad, a cargo de la prestigiosa Pirotecnia Pirofantas\u00eda Carlos Caballer.<\/p>\n<p>16:30 h. PARTIDO DE FUTBOL, Jornada 11, Regional preferente Grupo 4<\/p>\n<p>entre El Benidorm y C.D. Contestano.<\/p>\n<p>16:30 h. XLIII Trofeo de Palomos Deportivos organizado por el Club de<\/p>\n<p>Colombicultura \u00abLa Isla\u00bb, en Barranco de Xixo.<\/p>\n<p>17:00 h. CONCIERTO extraordinario de la prestigiosa y querida UNI\u00d3N<\/p>\n<p>MUSICAL DE BENIDORM en la calle Gambo con el siguiente programa:<\/p>\n<p>Slava &#8211; Obertura &#8211; Leonard Bernstein<\/p>\n<p>El Caser\u00edo &#8211; Preludio de la Zarzuela &#8211; Jes\u00fas Guridi<\/p>\n<p>El Padrino &#8211; Nino Rota \/ Carmen Coppola<\/p>\n<p>El Barbero de Lavapi\u00e9s &#8211; Zarzuela &#8211; Barbieri<\/p>\n<p>Alma de Dios &#8211; Canci\u00f3n H\u00fangara &#8211; Jos\u00e9 Serrano<\/p>\n<p>West Side Story &#8211; Selection &#8211; Leonard Bernstein<\/p>\n<p>17:00 h. II Concurso Nacional de Recortadores J\u00f3venes Promesas con<\/p>\n<p>novillos-toros de Jos\u00e9 Ortega para los m\u00e1s valientes (recortes, quiebros y<\/p>\n<p>saltos). Detr\u00e1s, suelta de vaquillas para todo el p\u00fablico. Precio, 5\u20ac .<\/p>\n<p>19:00 h. SOLEMNE PROCESI\u00d3N en honor a la VIRGEN DEL SUFRAGIO, con<\/p>\n<p>asistencia de Autoridades, Reinas, Damas, Abanderado, Mayorales de Honor, Mayorales, Mayoralesas y pueblo de Benidorm, con el siguiente itinerario: Calle Mayor, Alameda del Alcalde D. Pedro Zaragoza Orts, Los \u00c1ngeles, Pintor Lozano, Virgen del Sufragio, Mart\u00ednez Alejos, Paseo de la Carretera, Santa Faz y Plaza de San Jaime. Al finalizar la Procesi\u00f3n se disparar\u00e1 la t\u00edpica ESTAMPETAa la Virgen del Sufragio en la plaza de San Jaime. En el interior del templo, se entonar\u00e1 la Salve Marinera por todos los Marineros de la Virgen, acompa\u00f1ados de la Uni\u00f3n Musical de Benidorm.<\/p>\n<p>23:00 h. En la plaza de San Jaime, se cantar\u00e1n las tradicionales COPLETES en<\/p>\n<p>honor a la Virgen del Sufragio, acompa\u00f1adas de la \u201cXirimita i Tabalet\u201d. Al finalizar las mismas, tendr\u00e1 lugar la Nit d\u2019Albaes (con 2 cantadors, versador, xirimita y tabalet) que recorrer\u00e1 las calles y pe\u00f1as del casco antiguo.<\/p>\n<p>23:30 h. Las BATUKADAS de la Comisi\u00f3n de Fiestas 2012 recorrer\u00e1n las calles m\u00e1s c\u00e9ntricas de la ciudad, llenando de m\u00fasica y fiesta la noche, partiendo de la Carpa de la Comisi\u00f3n situado en la Plaza SS.MM. los Reyes de Espa\u00f1a.<\/p>\n<p>00:00 h. Noches de POP ROCK local con actuaci\u00f3n de los grupos locales<\/p>\n<p>MALDITA ILUSI\u00d3N y LOKOS DE ATAR en la C\/ Tomas Ortu\u00f1o &#8211; El Huerto de<\/p>\n<p>Col\u00f3n.<\/p>\n<p>00:00 h. Guerra de Bandas en C\/ Gambo. Organizado por varias pe\u00f1as.<\/p>\n<p>00:30 En la plaza SSMM los Reyes de Espa\u00f1a la Comisi\u00f3n de Fiestas Mayores Patronales organiza el RECORD MUNDIAL DEL GIN TONIC M\u00c1S GRANDE y todav\u00eda m\u00e1s\u2026 Los 40 PRINCIPALES amenizar\u00e1n con una extraordinaria velada musical.<\/p>\n<p>01:30 ENTREGA DE PREMIOS de los engalanamientos de calles y pe\u00f1as en la Plaza SSMM los Reyes de Espa\u00f1a.<\/p>\n<p><b>LUNES, 12 DE NOVIEMBRE D\u00cdA DE SAN JAIME AP\u00d3STOL<\/b><\/p>\n<p>08:00 h. BOMBARDEO A\u00c9REO desde la Plaza del Castillo.<\/p>\n<p>09:00 &#8211; 19:00 Concurso provincial de PETANCA.<\/p>\n<p>10:30 h. Recogida de las Reinas de las Fiestas y sus Cortes de Honor por los Mayorales y Mayoralesas acompa\u00f1ados por las bandas de m\u00fasica, dirigi\u00e9ndose a la plaza de SSMM los Reyes de Espa\u00f1a, y hasta el Torrej\u00f3 desde donde, junto a las Autoridades de nuestra ciudad, se desplazar\u00e1n a la Iglesia de San Jaime y Santa Ana.<\/p>\n<p>De 11:00 a 14:00. h. GRAN PARQUE INFANTIL en la Plaza SS.MM. Los Reyes<\/p>\n<p>de Espa\u00f1a organizado por la Comisi\u00f3n de Fiestas Mayores Patronales 2012 y la asociaci\u00f3n de penyas<\/p>\n<p>11:30 h. SOLEMNE CONCELEBRACI\u00d3N EUCAR\u00cdSTICA en honor a nuestro<\/p>\n<p>PATR\u00d3N SAN JAIME AP\u00d3STOL en la Iglesia de San Jaime y Santa Ana,<\/p>\n<p>presidida por el Rvdo. D. Luis L\u00f3pez Hern\u00e1ndez, P\u00e1rroco de San Jaime y Santa Ana con asistencia de Autoridades, Reinas, Damas, Abanderado, Mayorales de Honor, Autoridades, Comisi\u00f3n de Fiestas Mayores Patronales 2011 y todo el pueblo de Benidorm. La agrupaci\u00f3n coral de Benidorm dirigida por D. Luis Segu\u00ed Campa\u00f1 interpretar\u00e1 la I Pontifical del Laurentius Perosi presb\u00edtero.<\/p>\n<p>BOMBARDEO a la salida de misa. Al finalizar, PASACALLES a cargo de las<\/p>\n<p>bandas de la Comisi\u00f3n.<\/p>\n<p>12:30 h. PUFF EL DRAG\u00d3N, Espect\u00e1culo de teatro de calle itinerante muy<\/p>\n<p>participativo para todos los ni\u00f1os en la plaza SSMM Los Reyes De Espa\u00f1a.<\/p>\n<p>De 13:00 a 14:00: Degustaci\u00f3n de cerveza por gentileza de cerveza Cruz<\/p>\n<p>Campo (hasta agotar existencias) en la plaza de SSMM Los Reyes de Espa\u00f1a.<\/p>\n<p>14:00 h. SUPER-MASCLET\u00c1 DIGITAL, en la plaza la Hispanidad, a cargo de la prestigiosa Pirofantas\u00eda Carlos Caballer<\/p>\n<p>16:30 h. XLIII Trofeo de Palomos Deportivos organizado por el Club de<\/p>\n<p>Colombicultura \u00abLa Isla\u00bb, en Barranco de Xixo.<\/p>\n<p>19:00 h. SOLEMNE PROCESI\u00d3N en honor a nuestro PATR\u00d3N SAN JAIME<\/p>\n<p>APOSTOL con asistencia de Autoridades, Reinas, Damas, Abanderado,<\/p>\n<p>Mayorales de Honor, Mayorales y Mayoralesas, y pueblo de Benidorm, con el siguiente itinerario: Calle Mayor, Alameda del Alcalde D. Pedro Zaragoza Orts,<\/p>\n<p>Paseo de la Carretera, Santa Faz y Plaza de San Jaime.<\/p>\n<p>Al finalizar la Procesi\u00f3n se disparar\u00e1 la tradicional ESTAMPETA a San Jaime Ap\u00f3stol. En el interior del templo, se cantar\u00e1 el himno a nuestro Santo Patr\u00f3n.<\/p>\n<p>Y como es tradicional, con el inter\u00e9s y la expectaci\u00f3n habitual, el P\u00e1rroco de San Jaime y Santa Ana, D. Luis L\u00f3pez Hern\u00e1ndez proceder\u00e1 a la lectura de mayorales y mayoralesas de la Comisi\u00f3n de Fiestas Mayores Patronales del a\u00f1o 2013.<\/p>\n<p>23:30 h. PASACALLES con CHARANGA, partiendo de la Carpa de la Comisi\u00f3n, recorriendo las calles hasta altas horas de la madrugada.<\/p>\n<p>00:00 h. En el Huerto de Col\u00f3n ORQUESTA patrocinada por la Asociaci\u00f3n de Penyas.<\/p>\n<p>00:30 h. NOCHE SUPER-DJ\u2019s con FONSI NIETO (ex piloto de Motociclismo y<\/p>\n<p>actual DJ), Oscar L. y otros grandes DJ\u2019s de la zona y con actuaciones sorpresa en la plaza SSMM Los Reyes de Espa\u00f1a.<\/p>\n<p><b>MARTES, 13 DE NOVIEMBRE<\/b><\/p>\n<p>08:00 h. BOMBARDEO A\u00c9REO desde la Plaza del Castillo.<\/p>\n<p>09:00-19:00 Concurso provincial de PETANCA organizado por el club de<\/p>\n<p>petanca playa de Benidorm en las pistas de Mercasa.<\/p>\n<p>09:30 h. Recogida de las Reinas de las Fiestas y sus Cortes de Honor por los Mayorales y Mayoralesas acompa\u00f1ados por las bandas de m\u00fasica, dirigi\u00e9ndose a la plaza de SSMM los Reyes de Espa\u00f1a, y hasta el Torrej\u00f3 desde donde, junto a las Autoridades de nuestra ciudad, se desplazar\u00e1n a la Iglesia de San Jaime y Santa Ana.<\/p>\n<p>10:30 h. En la Iglesia de San Jaime y Santa Ana, MISA DE R\u00c9QUIEM<\/p>\n<p>De 11:00 a 14:00 h. GRAN PARQUE INFANTIL en la Plaza SS.MM. Los Reyes<\/p>\n<p>de Espa\u00f1a organizado conjuntamente por la Asociaci\u00f3n de Pe\u00f1as y la<\/p>\n<p>Comisi\u00f3n de Fiestas Mayores Patronales 2012.<\/p>\n<p>12:00 h. Actuaci\u00f3n de RONNIE MCDONALD para todos los ni\u00f1os con juegos y premios en la Plaza SSMM Los Reyes de Espa\u00f1a. Patrocinado por McDonalds Benidorm Centro (Plaza La Hispanidad) y McDonalds Playa (Rinc\u00f3n de Loix)<\/p>\n<p>12:30 h. SARDINADA en el Rinc\u00f3n de Loix ofrecida por la Falla del Rinc\u00f3n y patrocinada por la Comisi\u00f3n de Fiestas Mayores Patronales amenizada por una de nuestras prestigiosas bandas de m\u00fasica.<\/p>\n<p>De 13:00 a 14:00 h.: Degustaci\u00f3n de cerveza por gentileza de cerveza Cruz Campo (hasta agotar existencias) en la plaza de SSMM Los Reyes de Espa\u00f1a.<\/p>\n<p>14:00 h. SUP\u00c8R MASCLET\u00c1 DIGITAL en la Plaza la Hispanidad, a cargo de la prestigiosa Pirofantas\u00eda Carlos Caballer.<\/p>\n<p>16:30 h. XLIII Trofeo de Palomos Deportivos organizado por el Club de<\/p>\n<p>Colombicultura \u00abLa Isla\u00bb, en Barranco de Xixo.<\/p>\n<p>17:00 h. Espect\u00e1culo \u201cVERBENA INFANTIL\u201d de Pampol Teatre, Mario<\/p>\n<p>Caballero en C\/ Tom\u00e1s Ortu\u00f1o-Huerto de Col\u00f3n, patrocinado por la Diputaci\u00f3n Provincial de Alicante.<\/p>\n<p>19:00 h. GRAN DESFILE DEL HUMOR<\/p>\n<p>23:00 h EXTRAORDINARIA MASCLETA MIXTA DIGITAL a cargo de la<\/p>\n<p>prestigiosa Pirofantas\u00eda Carlos Caballer en la plaza de la Hispanidad.<\/p>\n<p>23:30 h. PASACALLES con BATUKADA, partiendo de la Carpa de la Comisi\u00f3n, recorriendo las calles hasta altas horas de la madrugada.<\/p>\n<p>00:30 h. GRAN CONCIERTO en la plaza de SSMM Los Reyes de Espa\u00f1a<\/p>\n<p>de NANCYS RUBIAS, grupo musical de punk, pop, glam y electr\u00f3nica liderado por Mario Vaquerizo (marido de Alaska).<\/p>\n<p>02:00 h. ENTREGA DE PREMIOS del Desfile del Humor en la plaza SSMM Los<\/p>\n<p>Reyes de Espa\u00f1a.<\/p>\n<p>Al finalizar el concierto, ESPECTACULAR CORREFOC, por XARXA TEATRE,<\/p>\n<p>quienes mezclando la m\u00fasica, los efectos pirot\u00e9cnicos y lum\u00ednicos, penetran por todos los sentidos. Llevar\u00e1 el siguiente recorrido: Plaza de S.S.M.M los Reyes de Espa\u00f1a, Avda L\u2019Aig\u00fcera, Hondo, Ruzafa, Plaza La Creu, Alameda Pedro Zaragoza, Malp\u00e1s, Plaza San Jaime, Avda. Mare de Deu del Sofratge(Playa), Martinez Alejos, Herrer\u00edas; con un grandioso espect\u00e1culo final en la plaza del Ayuntamiento (SSMM Los Reyes de Espa\u00f1a).<\/p>\n<p><b>MIERCOLES, 14 DE NOVIEMBRE<\/b><\/p>\n<p>08:00 h. BOMBARDEO A\u00c9REO desde la Plaza del Castillo.<\/p>\n<p>09:00-19:00 h. Concurso provincial de PETANCA.<\/p>\n<p>11:00 h. DIA DEL NI\u00d1O. GRAN PARQUE INFANTIL en la Plaza de SS.MM. Los<\/p>\n<p>Reyes de Espa\u00f1a.<\/p>\n<p>11:30 h. FESTA DE LES FESTES<\/p>\n<p>Concentraci\u00f3n de las diferentes entidades festeras de Benidorm en la Plaza de Neptuno, Parque de Elche y Plaza de la Hispanidad, para dirigirse en pasacalles hasta la Plaza SS.MM Los Reyes de Espa\u00f1a, donde ser\u00e1n recibidospor las Reinas, Cortes de Honor y Comisi\u00f3n de Fiestas Mayores Patronales2012, d\u00e1ndoles la bienvenida y ofreci\u00e9ndoles regalos y un vino de honor.<\/p>\n<p>12:30 h. RATOLINS Actuaci\u00f3n \u201cDebajo de un bot\u00f3n\u201d, espect\u00e1culo teatromusical y participativo para todos los ni\u00f1os en la plaza SSMM los Reyes de<\/p>\n<p>Espa\u00f1a. Al finalizar se disparar\u00e1 200M DE TRACA DE CARAMELOS Y<\/p>\n<p>MASCLET\u00c1 INFANTIL.<\/p>\n<p>16:30 h. XLIII Trofeo de Palomos Deportivos organizado por el Club de<\/p>\n<p>Colombicultura \u00abLa Isla\u00bb, en Barranco de Xixo.<\/p>\n<p>17:00 h. Concentraci\u00f3n en el Parque de Elche por las distintas Entidades<\/p>\n<p>Festeras y Asociaciones con sus respectivas bandas de m\u00fasica y carrozas.<\/p>\n<p>17:30 h. Inicio del grandioso y multitudinario \u201cDESFILE DE CARROZAS\u201d, Recorrido: C\/ Almendros, Marte, Venus, Ruzafa, Mart\u00ednez Alejos y Gambo finalizando en la Plaza de la Hispanidad.<\/p>\n<p>Al finalizar el desfile de carrozas GRANDIOSO, ESPECTACULAR Y NOVEDOSO CASTILLO DE FUEGOS ARTIFICIALES, en la Playa de Poniente.<\/p>\n<div>\n<br \/><span>Un saludo<\/span><\/p>\n<p><span>Hotel El Palmeral, Hotel en la Playa de Benidorm<\/span><br \/><a href=\"https:\/\/hotelpalmeral.com\/en\/\"><span>www.hotelpalmeral.com<\/span><\/a><br \/><span>Telf.:965 850 176<\/span>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>VIERNES, 09 DE NOVIEMBRE 18:00 h. &#8211; INAUGURACI\u00d3N OFICIAL DEL ALUMBRADO ARTISTICO, en la calle Mart\u00ednez Alejos por nuestra Reina Mayor la Srta. Andrea Ripoll Llorca ynuestra Reina Infantil la Ni\u00f1a Andrea Nieto Carrillo, junto a sus Cortes de Honor, acompa\u00f1ados por un grupo de m\u00fasicos de la prestigiosa Uni\u00f3n Musical de Benidorm. 18:30 h. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1735","post","type-post","status-publish","format-standard","hentry","category-agenda-cultural-y-de-ocio-de-benidorm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Programa de fiestas Patronales de Benidorm 2012 - Hotel El Palmeral<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/hotelpalmeral.com\/en\/programa-de-fiestas-patronales-de-benidorm-2012\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_GB\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Programa de fiestas Patronales de Benidorm 2012 - Hotel El Palmeral\" \/>\r\n<meta property=\"og:description\" content=\"VIERNES, 09 DE NOVIEMBRE 18:00 h. &#8211; INAUGURACI\u00d3N OFICIAL DEL ALUMBRADO ARTISTICO, en la calle Mart\u00ednez Alejos por nuestra Reina Mayor la Srta. Andrea Ripoll Llorca ynuestra Reina Infantil la Ni\u00f1a Andrea Nieto Carrillo, junto a sus Cortes de Honor, acompa\u00f1ados por un grupo de m\u00fasicos de la prestigiosa Uni\u00f3n Musical de Benidorm. 18:30 h. [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/hotelpalmeral.com\/en\/programa-de-fiestas-patronales-de-benidorm-2012\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Hotel El Palmeral\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HotelPalmeralBenidorm\" \/>\r\n<meta property=\"article:published_time\" content=\"2012-11-07T16:59:00+00:00\" \/>\r\n<meta name=\"author\" content=\"admin_palmeral\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@hotelelpalmeral\" \/>\r\n<meta name=\"twitter:site\" content=\"@hotelelpalmeral\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_palmeral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/\"},\"author\":{\"name\":\"admin_palmeral\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/person\\\/c8066d1b13fdf1bac6d45a1394738ca6\"},\"headline\":\"Programa de fiestas Patronales de Benidorm 2012\",\"datePublished\":\"2012-11-07T16:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/\"},\"wordCount\":2673,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#organization\"},\"articleSection\":[\"Agenda cultural y de ocio de Benidorm\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/\",\"name\":\"Programa de fiestas Patronales de Benidorm 2012 - Hotel El Palmeral\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#website\"},\"datePublished\":\"2012-11-07T16:59:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/programa-de-fiestas-patronales-de-benidorm-2012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hotelpalmeral.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programa de fiestas Patronales de Benidorm 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#website\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/\",\"name\":\"Hotel El Palmeral\",\"description\":\"Hotel en Benidorm\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotelpalmeral.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#organization\",\"name\":\"Hotel El Palmeral\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo-footer.png\",\"contentUrl\":\"https:\\\/\\\/hotelpalmeral.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo-footer.png\",\"width\":229,\"height\":265,\"caption\":\"Hotel El Palmeral\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HotelPalmeralBenidorm\",\"https:\\\/\\\/x.com\\\/hotelelpalmeral\",\"https:\\\/\\\/www.instagram.com\\\/hotelpalmeralbenidorm\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hotelpalmeral.com\\\/#\\\/schema\\\/person\\\/c8066d1b13fdf1bac6d45a1394738ca6\",\"name\":\"admin_palmeral\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g\",\"caption\":\"admin_palmeral\"},\"sameAs\":[\"http:\\\/\\\/hotelpalmeral.com\"],\"url\":\"https:\\\/\\\/hotelpalmeral.com\\\/en\\\/author\\\/admin_palmeral\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programa de fiestas Patronales de Benidorm 2012 - Hotel El Palmeral","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelpalmeral.com\/en\/programa-de-fiestas-patronales-de-benidorm-2012\/","og_locale":"en_GB","og_type":"article","og_title":"Programa de fiestas Patronales de Benidorm 2012 - Hotel El Palmeral","og_description":"VIERNES, 09 DE NOVIEMBRE 18:00 h. &#8211; INAUGURACI\u00d3N OFICIAL DEL ALUMBRADO ARTISTICO, en la calle Mart\u00ednez Alejos por nuestra Reina Mayor la Srta. Andrea Ripoll Llorca ynuestra Reina Infantil la Ni\u00f1a Andrea Nieto Carrillo, junto a sus Cortes de Honor, acompa\u00f1ados por un grupo de m\u00fasicos de la prestigiosa Uni\u00f3n Musical de Benidorm. 18:30 h. [&hellip;]","og_url":"https:\/\/hotelpalmeral.com\/en\/programa-de-fiestas-patronales-de-benidorm-2012\/","og_site_name":"Hotel El Palmeral","article_publisher":"https:\/\/www.facebook.com\/HotelPalmeralBenidorm","article_published_time":"2012-11-07T16:59:00+00:00","author":"admin_palmeral","twitter_card":"summary_large_image","twitter_creator":"@hotelelpalmeral","twitter_site":"@hotelelpalmeral","twitter_misc":{"Written by":"admin_palmeral","Estimated reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/#article","isPartOf":{"@id":"https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/"},"author":{"name":"admin_palmeral","@id":"https:\/\/hotelpalmeral.com\/#\/schema\/person\/c8066d1b13fdf1bac6d45a1394738ca6"},"headline":"Programa de fiestas Patronales de Benidorm 2012","datePublished":"2012-11-07T16:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/"},"wordCount":2673,"commentCount":0,"publisher":{"@id":"https:\/\/hotelpalmeral.com\/#organization"},"articleSection":["Agenda cultural y de ocio de Benidorm"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/","url":"https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/","name":"Programa de fiestas Patronales de Benidorm 2012 - Hotel El Palmeral","isPartOf":{"@id":"https:\/\/hotelpalmeral.com\/#website"},"datePublished":"2012-11-07T16:59:00+00:00","breadcrumb":{"@id":"https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotelpalmeral.com\/programa-de-fiestas-patronales-de-benidorm-2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hotelpalmeral.com\/"},{"@type":"ListItem","position":2,"name":"Programa de fiestas Patronales de Benidorm 2012"}]},{"@type":"WebSite","@id":"https:\/\/hotelpalmeral.com\/#website","url":"https:\/\/hotelpalmeral.com\/","name":"Hotel El Palmeral","description":"Hotel en Benidorm","publisher":{"@id":"https:\/\/hotelpalmeral.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelpalmeral.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/hotelpalmeral.com\/#organization","name":"Hotel El Palmeral","url":"https:\/\/hotelpalmeral.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/hotelpalmeral.com\/#\/schema\/logo\/image\/","url":"https:\/\/hotelpalmeral.com\/wp-content\/uploads\/2023\/03\/Logo-footer.png","contentUrl":"https:\/\/hotelpalmeral.com\/wp-content\/uploads\/2023\/03\/Logo-footer.png","width":229,"height":265,"caption":"Hotel El Palmeral"},"image":{"@id":"https:\/\/hotelpalmeral.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HotelPalmeralBenidorm","https:\/\/x.com\/hotelelpalmeral","https:\/\/www.instagram.com\/hotelpalmeralbenidorm\/"]},{"@type":"Person","@id":"https:\/\/hotelpalmeral.com\/#\/schema\/person\/c8066d1b13fdf1bac6d45a1394738ca6","name":"admin_palmeral","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b12524dda5bc713fd067188ac2e02862b3e463150f6095efe68cfd0e19d3b11?s=96&d=mm&r=g","caption":"admin_palmeral"},"sameAs":["http:\/\/hotelpalmeral.com"],"url":"https:\/\/hotelpalmeral.com\/en\/author\/admin_palmeral\/"}]}},"_links":{"self":[{"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/posts\/1735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/comments?post=1735"}],"version-history":[{"count":0,"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/posts\/1735\/revisions"}],"wp:attachment":[{"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/media?parent=1735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/categories?post=1735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotelpalmeral.com\/en\/wp-json\/wp\/v2\/tags?post=1735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}